{"id":2218,"date":"2024-07-04T15:07:31","date_gmt":"2024-07-04T13:07:31","guid":{"rendered":"https:\/\/schlitzer-destillerie.de\/magazin\/?p=2218"},"modified":"2024-07-04T16:00:57","modified_gmt":"2024-07-04T14:00:57","slug":"erfrischender-citrus-gin-slushy-fuer-den-sommer","status":"publish","type":"post","link":"https:\/\/schlitzer-destillerie.de\/magazin\/erfrischender-citrus-gin-slushy-fuer-den-sommer\/","title":{"rendered":"Erfrischender Citrus Gin Slushy f\u00fcr den Sommer"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8220;1&#8243; _builder_version=&#8220;4.16&#8243; global_colors_info=&#8220;{}&#8220;][et_pb_row _builder_version=&#8220;4.16&#8243; background_size=&#8220;initial&#8220; background_position=&#8220;top_left&#8220; background_repeat=&#8220;repeat&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;4.16&#8243; custom_padding=&#8220;|||&#8220; global_colors_info=&#8220;{}&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_text admin_label=&#8220;Einleitungs-Text&#8220; _builder_version=&#8220;4.25.1&#8243; text_font=&#8220;||||||||&#8220; background_size=&#8220;initial&#8220; background_position=&#8220;top_left&#8220; background_repeat=&#8220;repeat&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<h2>Erfrischender Genuss: Der perfekte Citrus Gin Slushy f\u00fcr hei\u00dfe Sommertage<\/h2>\n<p>Wenn Sie auf der Suche nach einer erfrischenden Alternative zum klassischen Aperol Slush sind, sollten Sie unbedingt den Citrus Gin Slushy probieren. Dieses k\u00f6stliche Getr\u00e4nk vereint die spritzigen Aromen von Burgen Citrus Gin mit dem erfrischenden Geschmack von Zitronensorbet und einem Hauch von Tonic Water. Perfekt f\u00fcr hei\u00dfe Sommertage oder als au\u00dfergew\u00f6hnlicher Aperitif, bringt der Citrus Gin Slushy eine belebende Abwechslung in Ihre Cocktailauswahl.<\/p>\n<p>[\/et_pb_text][et_pb_code _builder_version=&#8220;4.25.1&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;]<style>\n    #zrdn-recipe-container {background-color:#ffffff;}#zrdn-recipe-container {border-color:#000000;}#zrdn-recipe-container, #zrdn-recipe-container h2, #zrdn-recipe-container h3, #zrdn-recipe-container h4 {color:#000000;}                   #zrdn-recipe-container ol.zrdn-bordered li:before,\n            #zrdn-recipe-container ul.zrdn-bordered li:before{\n                border: 2px solid #000000;\n                color: #000000;\n            }\n            #zrdn-recipe-container ol.zrdn-solid li:before,\n            #zrdn-recipe-container ul.zrdn-solid li:before{\n                background-color: #000000;\n            }\n            #zrdn-recipe-container ul.bullets li:before,\n            #zrdn-recipe-container ol.zrdn-counter li:before,\n            #zrdn-recipe-container ul.zrdn-counter li:before {\n                color: #000000;\n            }\n            #zrdn-recipe-container .zrdn-tag-item a, #zrdn-recipe-container .zrdn-tag-item{\n                color:#000000;\n            }\n       #zrdn-recipe-container {border-style:initial;}#zrdn-recipe-container a {color:#000000;}#zrdn-recipe-container {border-width:0px;}#zrdn-recipe-container {border-color:#000000;}#zrdn-recipe-container {border-radius:0px;}\n<\/style>\n        <style>\n\n            #zrdn-recipe-container .zrdn-color {color:#000000;}\n            #zrdn-recipe-container .zrdn-bg-color {background-color:#000000;}\n            \n                    <\/style>\n        <div id=\"zrdn-recipe-container\" class=\"default zrdn-recipe-86 zrdn-jump-to-link\" >\n    <div class=\"zrdn-block zrdn-block-100\">\n\t<div class=\"zrdn-block-wrap zrdn-recipe_title\"  ><h2 class=\"zrdn-element_recipe_title\">Citrus Gin Slushy Rezept<\/h2>\n<\/div>\n<div class=\"zrdn-block-wrap zrdn-VisitorRating\"  >    <div data-recipeid=\"86\" class=\"zrdn__rating__container\" id=\"zrdn-rating\">\n        <div class=\"ratings\">\n            <div class=\"zrdn__rating_print zrdn_four\"><\/div>\n            <div class=\"zrdn-ratings-container zrdn-hide-print\">\n                <label for=\"zrdn-rating-select\">\n                    <select id=\"zrdn-rating-select\" class=\"zrdn__rating\">\n                        <option value=\"\"><\/option>\n                                                        <option value=\"1\">1<\/option>\n                                                            <option value=\"2\">2<\/option>\n                                                            <option value=\"3\">3<\/option>\n                                                            <option selected value='4'>4<\/option>\n                                                            <option value=\"5\">5<\/option>\n                                                <\/select>\n                <\/label>\n             <\/div>\n\n            <div>\n\t\t                                <span class='zrdn__rating__user_rating'>\n                            <span class='zrdn__rating__user_rating_label'>Das Rezept bewerten <\/span>\n                            <span style='display: none' class='zrdn__rating__user_rating_value'><\/span>\n                        <\/span>\n\t\t                    <\/div>\n            <div class=\"zrdn-ratings-divider\">|<\/div>\n            <div>\n\t\t                            <div class='zrdn__rating__count_label'><span class='zrdn__rating__count'>2<\/span>&nbsp;Bewertungen<\/div>\n\t\t                    <\/div>\n        <\/div>\n    <\/div>\n<\/div>\n<div class=\"zrdn-block-wrap zrdn-RecipeReviews\"  ><\/div>\n<div class=\"zrdn-block-wrap zrdn-actions\"  >\n\t\n\t<div class=\"zrdn-print-link\">\n\t\t\t\t<a title=\"Das Rezept ausdrucken\" href=\"javascript:void(0);\" onclick=\"zlrPrint('zrdn-recipe-container', 'https:\/\/schlitzer-destillerie.de\/magazin\/wp-content\/plugins\/zip-recipes-lover\/'); return false\" rel=\"nofollow\">\n            <img decoding=\"async\" src=\"https:\/\/schlitzer-destillerie.de\/magazin\/wp-content\/plugins\/zip-recipes-lover\/\/images\/print.png\" alt=\"Das Rezept ausdrucken\">\n\t\t<\/a>\n\t<\/div>\n\n    \n\t\n\t<\/div>\n<div class=\"zrdn-block-wrap zrdn-recipe_image\"  >\t        <div class=\"zrdn-recipe-image zrdn-hide-print zrdn-element_recipe_image\">\n            <img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/schlitzer-destillerie.de\/magazin\/wp-content\/uploads\/2024\/06\/Gin-Lemon-Slushy-Cocktail-800x600.webp\" class=\"attachment-zrdn_recipe_image_main size-zrdn_recipe_image_main\" alt=\"Cocktail in einem Glas mit Zitronenscheibe, verschwommene Flasche im Hintergrund, bunter Untergrund.\" srcset=\"https:\/\/schlitzer-destillerie.de\/magazin\/wp-content\/uploads\/2024\/06\/Gin-Lemon-Slushy-Cocktail-800x600.webp 800w, https:\/\/schlitzer-destillerie.de\/magazin\/wp-content\/uploads\/2024\/06\/Gin-Lemon-Slushy-Cocktail-480x319.webp 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 800px, 100vw\" \/>\t    <\/div>\n\t<\/div>\n\n<\/div><div class=\"zrdn-block zrdn-block-50\">\n\t<div class=\"zrdn-block-wrap zrdn-ingredients\"  ><h3 class=\"zrdn-recipe-label zrdn-ingredients-label\">\n    Zutaten<\/h3>\n\n\n<ul class=\"zrdn-list zrdn-ingredients-list bullets zrdn-element_ingredients\">\n            <li>3 cl Burgen Citrus Gin\r<\/li>\n\n            \n            <li>1 Kugel Zitronensorbet\r<\/li>\n\n            \n            <li>1 kleine Handvoll Eisw\u00fcrfel\r<\/li>\n\n            \n            <li>3 cl Tonic Water\r<\/li>\n\n            \n            <li>1,5 cl Zuckersirup (nach Geschmack)<\/li>\n\n            <\/ul>\n\n<\/div>\n\n<\/div><div class=\"zrdn-block zrdn-block-50\">\n\t<div class=\"zrdn-block-wrap zrdn-details\"  >    <div class=\"zrdn-details-item\">\n        <div class=\"zrdn-recipe-label\">\n\t        Personen        <\/div>\n\t    <div class=\"zrdn-value zrdn-yield zrdn-element_yield\">1<\/div>\n    <\/div>\n\n    <div class=\"zrdn-details-item zrdn-serving-size\">\n        <div class=\"zrdn-recipe-label\">\n\t        Portionsgr\u00f6\u00dfe        <\/div>\n        <div class=\"zrdn-value zrdn-element_serving_size\">1 Cocktail<\/div>\n    <\/div>\n\n\t<div class=\"zrdn-details-item zrdn-prep-time\">\n        <div class=\"zrdn-recipe-label\">\n\t        Vorbereitungszeit        <\/div>\n        <div class=\"zrdn-value zrdn-element_prep_time\">5 Minuten<\/div>\n\t<\/div>\n\n\n\n\t<div class=\"zrdn-details-item zrdn-total-time\">\n        <div class=\"zrdn-recipe-label\">\n\t        Gesamtzeit        <\/div>\n        <div class=\"zrdn-value zrdn-element_total_time\">5 Minuten<\/div>\n\t<\/div>\n\n\n\n\n\n\n<\/div>\n<div class=\"zrdn-block-wrap zrdn-social_sharing\"  ><h4 class=\"zrdn-recipe-label zrdn-social-sharing-label\">Teile auf sozialen Netzwerken<\/h4>\n<script>\n    function zrdnPopupCenter(url, title, w, h) {\n        \/\/ Fixes dual-screen position                         Most browsers      Firefox\n        var dualScreenLeft = window.screenLeft != undefined ? window.screenLeft : window.screenX;\n        var dualScreenTop = window.screenTop != undefined ? window.screenTop : window.screenY;\n        var width = window.innerWidth ? window.innerWidth : document.documentElement.clientWidth ? document.documentElement.clientWidth : screen.width;\n        var height = window.innerHeight ? window.innerHeight : document.documentElement.clientHeight ? document.documentElement.clientHeight : screen.height;\n        var left = ((width \/ 2) - (w \/ 2)) + dualScreenLeft;\n        var top = ((height \/ 2) - (h \/ 2)) + dualScreenTop;\n        var newWindow = window.open(url, title, 'scrollbars=yes, width=' + w + ', height=' + h + ', top=' + top + ', left=' + left);\n        if (window.focus) {newWindow.focus();}\n    }\n<\/script>\n<div class=\"zrdn-social-container\">\n            <a class=\"zrdn-share facebook\"\n           href=\"#\" onClick=\"zrdnPopupCenter('https:\/\/www.facebook.com\/share.php?u=https:\/\/schlitzer-destillerie.de\/magazin\/erfrischender-citrus-gin-slushy-fuer-den-sommer\/&width&layout=standard&action=share&show_faces=true&share=true&height=80','Facebook',600, 500); return false;\">\n            <svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\"\n\t width=\"32px\" height=\"32px\" viewBox=\"0 0 32 32\" enable-background=\"new 0 0 32 32\" xml:space=\"preserve\">\n<path id=\"White_2_\" fill=\"#3b5998\" d=\"M30.7,0H1.3C0.6,0,0,0.6,0,1.3v29.3C0,31.4,0.6,32,1.3,32H17V20h-4v-5h4v-4\n\tc0-4.1,2.6-6.2,6.3-6.2C25.1,4.8,26.6,5,27,5v4.3l-2.6,0c-2,0-2.5,1-2.5,2.4V15h5l-1,5h-4l0.1,12h8.6c0.7,0,1.3-0.6,1.3-1.3V1.3\n\tC32,0.6,31.4,0,30.7,0z\"\/>\n<\/svg>\n        <\/a>\n            <a class=\"zrdn-share pinterest\"\n           href='javascript:void((function()%7Bvar%20e=document.createElement(&apos;script&apos;);e.setAttribute(&apos;type&apos;,&apos;text\/javascript&apos;);e.setAttribute(&apos;charset&apos;,&apos;UTF-8&apos;);e.setAttribute(&apos;src&apos;,&apos;https:\/\/assets.pinterest.com\/js\/pinmarklet.js?r=&apos;+Math.random()*99999999);document.body.appendChild(e)%7D)());'>\n            <svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\"\n\t width=\"32px\" height=\"32px\" viewBox=\"0 0 32 32\" enable-background=\"new 0 0 32 32\" xml:space=\"preserve\">\n<path fill=\"#E60023\" d=\"M16,0C7.2,0,0,7.2,0,16c0,6.8,4.2,12.6,10.2,14.9c-0.1-1.3-0.3-3.2,0.1-4.6c0.3-1.2,1.9-8,1.9-8\n\ts-0.5-1-0.5-2.4c0-2.2,1.3-3.9,2.9-3.9c1.4,0,2,1,2,2.3c0,1.4-0.9,3.4-1.3,5.3c-0.4,1.6,0.8,2.9,2.4,2.9c2.8,0,5-3,5-7.3\n\tc0-3.8-2.8-6.5-6.7-6.5c-4.6,0-7.2,3.4-7.2,6.9c0,1.4,0.5,2.8,1.2,3.7c0.1,0.2,0.1,0.3,0.1,0.5c-0.1,0.5-0.4,1.6-0.4,1.8\n\tC9.5,21.9,9.3,22,9,21.8c-2-0.9-3.2-3.9-3.2-6.2c0-5,3.7-9.7,10.6-9.7c5.6,0,9.9,4,9.9,9.2c0,5.5-3.5,10-8.3,10\n\tc-1.6,0-3.1-0.8-3.7-1.8c0,0-0.8,3.1-1,3.8c-0.4,1.4-1.3,3.1-2,4.2c1.5,0.5,3.1,0.7,4.7,0.7c8.8,0,16-7.2,16-16C32,7.2,24.8,0,16,0z\n\t\"\/>\n<\/svg>\n        <\/a>\n            <a class=\"zrdn-share reddit\"\n           href=\"#\" onClick=\"zrdnPopupCenter('http:\/\/www.reddit.com\/submit?url=https:\/\/schlitzer-destillerie.de\/magazin\/erfrischender-citrus-gin-slushy-fuer-den-sommer\/&title=Citrus Gin Slushy Rezept','Reddit',600,500); return false;\">\n            <svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\"\n\t width=\"32px\" height=\"32px\" viewBox=\"0 0 32 32\" enable-background=\"new 0 0 32 32\" xml:space=\"preserve\">\n<path fill=\"#E60023\" d=\"M32,15.7c0-2.1-1.7-3.8-3.8-3.8c-0.9,0-1.8,0.3-2.4,0.9c-2.3-1.5-5.3-2.4-8.5-2.5l1.7-5.3L23.5,6\n\tc0.1,1.7,1.5,3,3.2,3c1.8,0,3.2-1.4,3.2-3.2c0-1.8-1.4-3.2-3.2-3.2c-1.2,0-2.3,0.7-2.9,1.7L18.5,3c-0.4-0.1-0.9,0.2-1,0.6l-2.1,6.5\n\tc-3.4,0.1-6.7,1-9.2,2.5c-0.7-0.5-1.5-0.8-2.4-0.8c-2.1,0-3.8,1.7-3.8,3.8c0,1.3,0.7,2.5,1.7,3.2c0,0.3-0.1,0.6-0.1,0.9\n\tc0,2.7,1.5,5.1,4.3,6.9c2.7,1.8,6.2,2.7,10,2.7c3.8,0,7.3-1,10-2.7c2.8-1.8,4.3-4.3,4.3-6.9c0-0.3,0-0.6-0.1-0.8\n\tC31.3,18.3,32,17.1,32,15.7z M26.7,4.3c0.8,0,1.5,0.7,1.5,1.5c0,0.8-0.7,1.5-1.5,1.5s-1.5-0.7-1.5-1.5C25.2,5,25.9,4.3,26.7,4.3z\n\t M9.1,18.1c0-1.2,1-2.2,2.2-2.2c1.2,0,2.2,1,2.2,2.2s-1,2.2-2.2,2.2C10.1,20.3,9.1,19.3,9.1,18.1z M21.3,24.5\n\tc-1.1,1.1-2.8,1.7-5.3,1.7c0,0,0,0,0,0c0,0,0,0,0,0c-2.4,0-4.1-0.5-5.3-1.7c-0.3-0.3-0.3-0.9,0-1.2c0.3-0.3,0.9-0.3,1.2,0\n\tc0.8,0.8,2.1,1.1,4,1.1c0,0,0,0,0,0c0,0,0,0,0,0c1.9,0,3.2-0.4,4-1.1c0.3-0.3,0.9-0.3,1.2,0C21.6,23.6,21.6,24.1,21.3,24.5z\n\t M20.8,20.3c-1.2,0-2.2-1-2.2-2.2s1-2.2,2.2-2.2c1.2,0,2.2,1,2.2,2.2S22,20.3,20.8,20.3z\"\/>\n<\/svg>\n        <\/a>\n            <a class=\"zrdn-share twitter\"\n           href=\"#\" onClick=\"zrdnPopupCenter('https:\/\/twitter.com\/share?url=https:\/\/schlitzer-destillerie.de\/magazin\/erfrischender-citrus-gin-slushy-fuer-den-sommer\/','Twitter',600,500); return false;\">\n            <svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\"\n\t width=\"32px\" height=\"32px\" viewBox=\"0 0 32 32\" enable-background=\"new 0 0 32 32\" xml:space=\"preserve\">\n<path fill=\"#1da1f2\" d=\"M32,6.1c-1.2,0.5-2.4,0.9-3.8,1c1.4-0.8,2.4-2.1,2.9-3.6c-1.3,0.8-2.7,1.3-4.2,1.6C25.7,3.8,24,3,22.2,3\n\tc-3.6,0-6.6,2.9-6.6,6.6c0,0.5,0.1,1,0.2,1.5C10.3,10.8,5.5,8.2,2.2,4.2c-0.6,1-0.9,2.1-0.9,3.3c0,2.3,1.2,4.3,2.9,5.5\n\tc-1.1,0-2.1-0.3-3-0.8c0,0,0,0.1,0,0.1c0,3.2,2.3,5.8,5.3,6.4c-0.6,0.1-1.1,0.2-1.7,0.2c-0.4,0-0.8,0-1.2-0.1\n\tc0.8,2.6,3.3,4.5,6.1,4.6c-2.2,1.8-5.1,2.8-8.2,2.8c-0.5,0-1.1,0-1.6-0.1C2.9,27.9,6.4,29,10.1,29c12.1,0,18.7-10,18.7-18.7\n\tc0-0.3,0-0.6,0-0.8C30,8.5,31.1,7.4,32,6.1z\"\/>\n<\/svg>\n        <\/a>\n            <a class=\"zrdn-share whatsapp\"\n           href=\"whatsapp:\/\/send?text=https:\/\/schlitzer-destillerie.de\/magazin\/erfrischender-citrus-gin-slushy-fuer-den-sommer\/\" data-action=\"\/share\/whatsapp\/share\">\n            <svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\"\n\t width=\"32px\" height=\"32px\" viewBox=\"0 0 32 32\" enable-background=\"new 0 0 32 32\" xml:space=\"preserve\">\n<path fill=\"#25d366\" d=\"M0.1,32l2.3-8.2c-1.4-2.4-2.1-5.1-2.1-7.9C0.2,7.1,7.3,0,16.1,0c4.2,0,8.2,1.7,11.2,4.7c3,3,4.6,7,4.6,11.2\n\tc0,8.7-7.1,15.9-15.9,15.9h0h0c-2.7,0-5.3-0.7-7.6-1.9L0.1,32z M8.9,26.9l0.5,0.3c2,1.2,4.3,1.8,6.7,1.8h0c7.3,0,13.2-5.9,13.2-13.2\n\tc0-3.5-1.4-6.8-3.9-9.3s-5.8-3.9-9.3-3.9C8.8,2.7,2.9,8.6,2.9,15.9c0,2.5,0.7,4.9,2,7l0.3,0.5l-1.3,4.9L8.9,26.9z\"\/>\n<path fill-rule=\"evenodd\" clip-rule=\"evenodd\" fill=\"#25d366\" d=\"M12.1,9.2c-0.3-0.8-0.6-0.7-0.9-0.7c-0.2,0-0.5,0-0.8,0\n\tc-0.3,0-0.7,0.1-1.1,0.5C9,9.4,8,10.4,8,12.3c0,2,1.4,3.8,1.6,4.1c0.2,0.3,2.8,4.3,6.8,6c0.9,0.4,1.7,0.7,2.3,0.8\n\tc0.9,0.3,1.8,0.3,2.5,0.2c0.8-0.1,2.3-1,2.7-1.9c0.3-0.9,0.3-1.7,0.2-1.9c-0.1-0.2-0.4-0.3-0.8-0.5C22.9,19,21,18,20.6,17.9\n\tc-0.4-0.1-0.6-0.2-0.9,0.2c-0.3,0.4-1,1.3-1.3,1.6c-0.2,0.3-0.5,0.3-0.9,0.1c-0.4-0.2-1.7-0.6-3.2-2c-1.2-1.1-2-2.3-2.2-2.7\n\tc-0.2-0.4,0-0.6,0.2-0.8c0.2-0.2,0.4-0.5,0.6-0.7c0.2-0.2,0.3-0.4,0.4-0.7c0.1-0.3,0.1-0.5,0-0.7C13.2,12,12.4,10,12.1,9.2z\"\/>\n<\/svg>\n        <\/a>\n    <\/div><\/div>\n\n<\/div><div class=\"zrdn-block zrdn-block-100\">\n\t<div class=\"zrdn-block-wrap zrdn-instructions\"  >    <h3 class=\"zrdn-recipe-label zrdn-instructions-label\">\n        Anleitung    <\/h3>\n<ol class=\"zrdn-list zrdn-instructions-list numbers  zrdn-element_instructions\">\n\t\t            <li>Geben Sie den Burgen Citrus Gin, das Zitronensorbet und die Eisw\u00fcrfel in einen Mixer.\r<\/li>\n\t\t\n\t\t            <li>Mixen Sie die Zutaten, bis eine gleichm\u00e4\u00dfige, slushyartige Konsistenz erreicht ist.\r<\/li>\n\t\t\n\t\t            <li>F\u00fcgen Sie das Tonic Water und den Zuckersirup hinzu und mixen Sie erneut kurz durch.\r<\/li>\n\t\t\n\t\t            <li>Gie\u00dfen Sie den Citrus Gin Slushy in ein gek\u00fchltes Glas und garnieren Sie nach Belieben mit einer Zitronenscheibe.<\/li>\n\t\t<\/ol><\/div>\n<div class=\"zrdn-block-wrap zrdn-notes\"  >    <h3 class=\"zrdn-recipe-label zrdn-notes-label\">Hinweis:<\/h3>\n\t<p class=\"zrdn-element_notes\">Genie\u00dfen Sie diesen fruchtig-frischen <a href=\"https:\/\/schlitzer-destillerie.de\/magazin\/erfrischender-citrus-gin-fizz-cocktail-einfaches-rezept\/\">Cocktail<\/a> und lassen Sie sich von der perfekten Mischung aus Gin und Zitrone verf\u00fchren. Ob auf der Terrasse, am Pool oder bei einem geselligen Abend mit Freunden \u2013 der Citrus Gin Slushy ist die perfekte Wahl, um die warme Jahreszeit stilvoll zu feiern.<br><\/p>\n<\/div>\n<div class=\"zrdn-block-wrap zrdn-video\"  >    <div class=\"zrdn-element_video_url\"> <div class=\"brlbs-cmpnt-container brlbs-cmpnt-content-blocker brlbs-cmpnt-with-individual-styles\" data-borlabs-cookie-content-blocker-id=\"youtube-content-blocker\" data-borlabs-cookie-content=\"PGlmcmFtZSBsb2FkaW5nPSJsYXp5IiB0aXRsZT0iRXJmcmlzY2hlbmRlciBDaXRydXMgR2luIFNsdXNoeSDigJMgRGFzIHBlcmZla3RlIFNvbW1lcmdldHLDpG5rISDwn42L8J+NuSIgd2lkdGg9IjU2MyIgaGVpZ2h0PSIxMDAwIiBzcmM9Imh0dHBzOi8vd3d3LnlvdXR1YmUtbm9jb29raWUuY29tL2VtYmVkL05vdk1RS0xNYkZVP2ZlYXR1cmU9b2VtYmVkIiAgYWxsb3c9ImFjY2VsZXJvbWV0ZXI7IGF1dG9wbGF5OyBjbGlwYm9hcmQtd3JpdGU7IGVuY3J5cHRlZC1tZWRpYTsgZ3lyb3Njb3BlOyBwaWN0dXJlLWluLXBpY3R1cmU7IHdlYi1zaGFyZSIgcmVmZXJyZXJwb2xpY3k9InN0cmljdC1vcmlnaW4td2hlbi1jcm9zcy1vcmlnaW4iIGFsbG93ZnVsbHNjcmVlbj48L2lmcmFtZT4=\"><div class=\"brlbs-cmpnt-cb-preset-c brlbs-cmpnt-cb-youtube\"> <div class=\"brlbs-cmpnt-cb-thumbnail\" style=\"background-image: url('https:\/\/schlitzer-destillerie.de\/magazin\/wp-content\/uploads\/borlabs-cookie\/1\/yt_NovMQKLMbFU_hqdefault.jpg')\"><\/div> <div class=\"brlbs-cmpnt-cb-main\"> <div class=\"brlbs-cmpnt-cb-play-button\"><\/div> <div class=\"brlbs-cmpnt-cb-content\"> <p class=\"brlbs-cmpnt-cb-description\">Sie sehen gerade einen Platzhalterinhalt von <strong>YouTube<\/strong>. Um auf den eigentlichen Inhalt zuzugreifen, klicken Sie auf die Schaltfl\u00e4che unten. Bitte beachten Sie, dass dabei Daten an Drittanbieter weitergegeben werden.<\/p> <a class=\"brlbs-cmpnt-cb-provider-toggle\" href=\"#\" data-borlabs-cookie-show-provider-information role=\"button\">Mehr Informationen<\/a> <\/div> <div class=\"brlbs-cmpnt-cb-buttons\"> <a class=\"brlbs-cmpnt-cb-btn\" href=\"#\" data-borlabs-cookie-unblock role=\"button\">Inhalt entsperren<\/a> <a class=\"brlbs-cmpnt-cb-btn\" href=\"#\" data-borlabs-cookie-accept-service role=\"button\" style=\"display: inherit\">Erforderlichen Service akzeptieren und Inhalte entsperren<\/a> <\/div> <\/div> <\/div><\/div><\/div>\n<\/div>\n\n<\/div><div class=\"zrdn-block zrdn-block-0 print\">\n\t<div class=\"zrdn-block-wrap zrdn-permalink\"  ><\/div>\n\n<\/div><div class=\"zrdn-block zrdn-block-0\">\n\t<div class=\"zrdn-block-wrap zrdn-jsonld\"  ><script type=\"application\/ld+json\">\n    {\"@context\":\"http:\\\/\\\/schema.org\",\"@type\":\"Recipe\",\"description\":\"Citrus Gin Slushy Rezept\",\"image\":[\"https:\\\/\\\/schlitzer-destillerie.de\\\/magazin\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Gin-Lemon-Slushy-Cocktail-250x250.webp\",\"https:\\\/\\\/schlitzer-destillerie.de\\\/magazin\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Gin-Lemon-Slushy-Cocktail-198x164.webp\",\"https:\\\/\\\/schlitzer-destillerie.de\\\/magazin\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Gin-Lemon-Slushy-Cocktail-320x200.webp\"],\"recipeIngredient\":[\"3 cl Burgen Citrus Gin\\r\",\"1 Kugel Zitronensorbet\\r\",\"1 kleine Handvoll Eisw\\u00fcrfel\\r\",\"3 cl Tonic Water\\r\",\"1,5 cl Zuckersirup (nach Geschmack)\"],\"name\":\"Citrus Gin Slushy Rezept\",\"recipeCategory\":\"Gin\",\"recipeCuisine\":\"Deutsch\",\"cookTime\":\"PT0H0M\",\"prepTime\":\"PT0H5M\",\"recipeInstructions\":[\"Geben Sie den Burgen Citrus Gin, das Zitronensorbet und die Eisw\\u00fcrfel in einen Mixer.\\r\",\"Mixen Sie die Zutaten, bis eine gleichm\\u00e4\\u00dfige, slushyartige Konsistenz erreicht ist.\\r\",\"F\\u00fcgen Sie das Tonic Water und den Zuckersirup hinzu und mixen Sie erneut kurz durch.\\r\",\"Gie\\u00dfen Sie den Citrus Gin Slushy in ein gek\\u00fchltes Glas und garnieren Sie nach Belieben mit einer Zitronenscheibe.\"],\"recipeYield\":\"1 Person\",\"keywords\":\"Cocktail,Gin\",\"video\":{\"@type\":\"VideoObject\",\"name\":\"Citrus Gin Slushy Rezept\",\"embedUrl\":\"https:\\\/\\\/youtube.com\\\/shorts\\\/NovMQKLMbFU?feature=share\",\"contentUrl\":\"https:\\\/\\\/youtube.com\\\/shorts\\\/NovMQKLMbFU?feature=share\",\"uploadDate\":\"2024-07-04\",\"description\":\"Citrus Gin Slushy Rezept\"},\"totalTime\":\"PT0H5M\",\"author\":{\"@type\":\"Person\",\"name\":\"Kai\"},\"aggregateRating\":{\"bestRating\":5,\"ratingValue\":4,\"itemReviewed\":\"Citrus Gin Slushy Rezept\",\"ratingCount\":2,\"worstRating\":1}}<\/script><\/div>\n\n<\/div>\n<\/div>[\/et_pb_code][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8220;4.24.2&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;4.23&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_text admin_label=&#8220;SEO Text&#8220; _builder_version=&#8220;4.25.1&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<h3>Die perfekte Erfrischung f\u00fcr Ihre Sommerparty<\/h3>\n<p>Ein Citrus Gin Slushy ist nicht nur ein Genuss f\u00fcr den Gaumen, sondern auch ein echter Hingucker auf jeder Sommerparty. Die leuchtende Farbe und die erfrischende Textur machen diesen Cocktail zu einem Highlight bei Ihren G\u00e4sten. Servieren Sie ihn in stilvollen Gl\u00e4sern und garnieren Sie mit frischen Zitronenscheiben oder Minzbl\u00e4ttern, um einen zus\u00e4tzlichen Hauch von Eleganz zu verleihen. Dieser Slushy ist die ideale Wahl, um Ihre Sommerabende unvergesslich zu machen.<\/p>\n<h3>Einfaches Rezept f\u00fcr den schnellen Genuss<\/h3>\n<p>Einer der gr\u00f6\u00dften Vorteile des Citrus Gin Slushy ist die einfache Zubereitung. Mit nur wenigen Zutaten und einem Mixer zaubern Sie in k\u00fcrzester Zeit eine k\u00f6stliche Erfrischung. Egal, ob Sie spontan G\u00e4ste bewirten oder sich selbst eine kleine Auszeit g\u00f6nnen m\u00f6chten \u2013 dieses Rezept gelingt immer. Passen Sie den Zuckersirup nach Ihrem Geschmack an, um die perfekte Balance zwischen S\u00fc\u00dfe und Frische zu finden. Genie\u00dfen Sie die unkomplizierte Zubereitung und lassen Sie sich von diesem sommerlichen Getr\u00e4nk verzaubern.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Erfrischender Genuss: Der perfekte Citrus Gin Slushy f\u00fcr hei\u00dfe Sommertage Wenn Sie auf der Suche nach einer erfrischenden Alternative zum klassischen Aperol Slush sind, sollten Sie unbedingt den Citrus Gin Slushy probieren. Dieses k\u00f6stliche Getr\u00e4nk vereint die spritzigen Aromen von Burgen Citrus Gin mit dem erfrischenden Geschmack von Zitronensorbet und einem Hauch von Tonic Water. [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":2221,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","wprm-recipe-roundup-name":"","wprm-recipe-roundup-description":"","footnotes":""},"categories":[8,1],"tags":[36,14],"class_list":["post-2218","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gin","category-cocktailrezepte-fuer-jeden-anlass","tag-cocktail","tag-gin"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Erfrischender Citrus Gin Slushy f\u00fcr den Sommer \ud83c\udf4b<\/title>\n<meta name=\"description\" content=\"Entdecken Sie den Citrus Gin Slushy \u2013 eine spritzige Mischung aus Burgen Citrus Gin, Zitronensorbet und Tonic Water. Ideal f\u00fcr hei\u00dfe Sommertage!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/schlitzer-destillerie.de\/magazin\/erfrischender-citrus-gin-slushy-fuer-den-sommer\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Erfrischender Citrus Gin Slushy f\u00fcr den Sommer \ud83c\udf4b\" \/>\n<meta property=\"og:description\" content=\"Entdecken Sie den Citrus Gin Slushy \u2013 eine spritzige Mischung aus Burgen Citrus Gin, Zitronensorbet und Tonic Water. Ideal f\u00fcr hei\u00dfe Sommertage!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/schlitzer-destillerie.de\/magazin\/erfrischender-citrus-gin-slushy-fuer-den-sommer\/\" \/>\n<meta property=\"og:site_name\" content=\"Magazin \u2013\u00a0Schlitzer Destillerie\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-04T13:07:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-04T14:00:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/schlitzer-destillerie.de\/magazin\/wp-content\/uploads\/2024\/06\/Gin-Lemon-Slushy-Cocktail.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"912\" \/>\n\t<meta property=\"og:image:height\" content=\"607\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Kai\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Kai\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/schlitzer-destillerie.de\\\/magazin\\\/erfrischender-citrus-gin-slushy-fuer-den-sommer\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/schlitzer-destillerie.de\\\/magazin\\\/erfrischender-citrus-gin-slushy-fuer-den-sommer\\\/\"},\"author\":{\"name\":\"Kai\",\"@id\":\"https:\\\/\\\/schlitzer-destillerie.de\\\/magazin\\\/#\\\/schema\\\/person\\\/9b641910652a16e469ed3efcce46eaa2\"},\"headline\":\"Erfrischender Citrus Gin Slushy f\u00fcr den Sommer\",\"datePublished\":\"2024-07-04T13:07:31+00:00\",\"dateModified\":\"2024-07-04T14:00:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/schlitzer-destillerie.de\\\/magazin\\\/erfrischender-citrus-gin-slushy-fuer-den-sommer\\\/\"},\"wordCount\":405,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/schlitzer-destillerie.de\\\/magazin\\\/erfrischender-citrus-gin-slushy-fuer-den-sommer\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/schlitzer-destillerie.de\\\/magazin\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Gin-Lemon-Slushy-Cocktail.webp\",\"keywords\":[\"Cocktail\",\"Gin\"],\"articleSection\":[\"Gin\",\"Rezepte\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/schlitzer-destillerie.de\\\/magazin\\\/erfrischender-citrus-gin-slushy-fuer-den-sommer\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/schlitzer-destillerie.de\\\/magazin\\\/erfrischender-citrus-gin-slushy-fuer-den-sommer\\\/\",\"url\":\"https:\\\/\\\/schlitzer-destillerie.de\\\/magazin\\\/erfrischender-citrus-gin-slushy-fuer-den-sommer\\\/\",\"name\":\"Erfrischender Citrus Gin Slushy f\u00fcr den Sommer \ud83c\udf4b\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/schlitzer-destillerie.de\\\/magazin\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/schlitzer-destillerie.de\\\/magazin\\\/erfrischender-citrus-gin-slushy-fuer-den-sommer\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/schlitzer-destillerie.de\\\/magazin\\\/erfrischender-citrus-gin-slushy-fuer-den-sommer\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/schlitzer-destillerie.de\\\/magazin\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Gin-Lemon-Slushy-Cocktail.webp\",\"datePublished\":\"2024-07-04T13:07:31+00:00\",\"dateModified\":\"2024-07-04T14:00:57+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/schlitzer-destillerie.de\\\/magazin\\\/#\\\/schema\\\/person\\\/9b641910652a16e469ed3efcce46eaa2\"},\"description\":\"Entdecken Sie den Citrus Gin Slushy \u2013 eine spritzige Mischung aus Burgen Citrus Gin, Zitronensorbet und Tonic Water. Ideal f\u00fcr hei\u00dfe Sommertage!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/schlitzer-destillerie.de\\\/magazin\\\/erfrischender-citrus-gin-slushy-fuer-den-sommer\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/schlitzer-destillerie.de\\\/magazin\\\/erfrischender-citrus-gin-slushy-fuer-den-sommer\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/schlitzer-destillerie.de\\\/magazin\\\/erfrischender-citrus-gin-slushy-fuer-den-sommer\\\/#primaryimage\",\"url\":\"https:\\\/\\\/schlitzer-destillerie.de\\\/magazin\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Gin-Lemon-Slushy-Cocktail.webp\",\"contentUrl\":\"https:\\\/\\\/schlitzer-destillerie.de\\\/magazin\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Gin-Lemon-Slushy-Cocktail.webp\",\"width\":912,\"height\":607,\"caption\":\"Cocktail in einem Glas mit Zitronenscheibe, verschwommene Flasche im Hintergrund, bunter Untergrund.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/schlitzer-destillerie.de\\\/magazin\\\/erfrischender-citrus-gin-slushy-fuer-den-sommer\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/schlitzer-destillerie.de\\\/magazin\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Erfrischender Citrus Gin Slushy f\u00fcr den Sommer\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/schlitzer-destillerie.de\\\/magazin\\\/#website\",\"url\":\"https:\\\/\\\/schlitzer-destillerie.de\\\/magazin\\\/\",\"name\":\"Magazin \u2013\u00a0Schlitzer Destillerie\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/schlitzer-destillerie.de\\\/magazin\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/schlitzer-destillerie.de\\\/magazin\\\/#\\\/schema\\\/person\\\/9b641910652a16e469ed3efcce46eaa2\",\"name\":\"Kai\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/646cb51eb5f7e2bf921a1de93786461c84e696826998c6579c7915d1cb32de1d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/646cb51eb5f7e2bf921a1de93786461c84e696826998c6579c7915d1cb32de1d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/646cb51eb5f7e2bf921a1de93786461c84e696826998c6579c7915d1cb32de1d?s=96&d=mm&r=g\",\"caption\":\"Kai\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Erfrischender Citrus Gin Slushy f\u00fcr den Sommer \ud83c\udf4b","description":"Entdecken Sie den Citrus Gin Slushy \u2013 eine spritzige Mischung aus Burgen Citrus Gin, Zitronensorbet und Tonic Water. Ideal f\u00fcr hei\u00dfe Sommertage!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/schlitzer-destillerie.de\/magazin\/erfrischender-citrus-gin-slushy-fuer-den-sommer\/","og_locale":"de_DE","og_type":"article","og_title":"Erfrischender Citrus Gin Slushy f\u00fcr den Sommer \ud83c\udf4b","og_description":"Entdecken Sie den Citrus Gin Slushy \u2013 eine spritzige Mischung aus Burgen Citrus Gin, Zitronensorbet und Tonic Water. Ideal f\u00fcr hei\u00dfe Sommertage!","og_url":"https:\/\/schlitzer-destillerie.de\/magazin\/erfrischender-citrus-gin-slushy-fuer-den-sommer\/","og_site_name":"Magazin \u2013\u00a0Schlitzer Destillerie","article_published_time":"2024-07-04T13:07:31+00:00","article_modified_time":"2024-07-04T14:00:57+00:00","og_image":[{"width":912,"height":607,"url":"https:\/\/schlitzer-destillerie.de\/magazin\/wp-content\/uploads\/2024\/06\/Gin-Lemon-Slushy-Cocktail.webp","type":"image\/webp"}],"author":"Kai","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Kai","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/schlitzer-destillerie.de\/magazin\/erfrischender-citrus-gin-slushy-fuer-den-sommer\/#article","isPartOf":{"@id":"https:\/\/schlitzer-destillerie.de\/magazin\/erfrischender-citrus-gin-slushy-fuer-den-sommer\/"},"author":{"name":"Kai","@id":"https:\/\/schlitzer-destillerie.de\/magazin\/#\/schema\/person\/9b641910652a16e469ed3efcce46eaa2"},"headline":"Erfrischender Citrus Gin Slushy f\u00fcr den Sommer","datePublished":"2024-07-04T13:07:31+00:00","dateModified":"2024-07-04T14:00:57+00:00","mainEntityOfPage":{"@id":"https:\/\/schlitzer-destillerie.de\/magazin\/erfrischender-citrus-gin-slushy-fuer-den-sommer\/"},"wordCount":405,"commentCount":0,"image":{"@id":"https:\/\/schlitzer-destillerie.de\/magazin\/erfrischender-citrus-gin-slushy-fuer-den-sommer\/#primaryimage"},"thumbnailUrl":"https:\/\/schlitzer-destillerie.de\/magazin\/wp-content\/uploads\/2024\/06\/Gin-Lemon-Slushy-Cocktail.webp","keywords":["Cocktail","Gin"],"articleSection":["Gin","Rezepte"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/schlitzer-destillerie.de\/magazin\/erfrischender-citrus-gin-slushy-fuer-den-sommer\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/schlitzer-destillerie.de\/magazin\/erfrischender-citrus-gin-slushy-fuer-den-sommer\/","url":"https:\/\/schlitzer-destillerie.de\/magazin\/erfrischender-citrus-gin-slushy-fuer-den-sommer\/","name":"Erfrischender Citrus Gin Slushy f\u00fcr den Sommer \ud83c\udf4b","isPartOf":{"@id":"https:\/\/schlitzer-destillerie.de\/magazin\/#website"},"primaryImageOfPage":{"@id":"https:\/\/schlitzer-destillerie.de\/magazin\/erfrischender-citrus-gin-slushy-fuer-den-sommer\/#primaryimage"},"image":{"@id":"https:\/\/schlitzer-destillerie.de\/magazin\/erfrischender-citrus-gin-slushy-fuer-den-sommer\/#primaryimage"},"thumbnailUrl":"https:\/\/schlitzer-destillerie.de\/magazin\/wp-content\/uploads\/2024\/06\/Gin-Lemon-Slushy-Cocktail.webp","datePublished":"2024-07-04T13:07:31+00:00","dateModified":"2024-07-04T14:00:57+00:00","author":{"@id":"https:\/\/schlitzer-destillerie.de\/magazin\/#\/schema\/person\/9b641910652a16e469ed3efcce46eaa2"},"description":"Entdecken Sie den Citrus Gin Slushy \u2013 eine spritzige Mischung aus Burgen Citrus Gin, Zitronensorbet und Tonic Water. Ideal f\u00fcr hei\u00dfe Sommertage!","breadcrumb":{"@id":"https:\/\/schlitzer-destillerie.de\/magazin\/erfrischender-citrus-gin-slushy-fuer-den-sommer\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/schlitzer-destillerie.de\/magazin\/erfrischender-citrus-gin-slushy-fuer-den-sommer\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/schlitzer-destillerie.de\/magazin\/erfrischender-citrus-gin-slushy-fuer-den-sommer\/#primaryimage","url":"https:\/\/schlitzer-destillerie.de\/magazin\/wp-content\/uploads\/2024\/06\/Gin-Lemon-Slushy-Cocktail.webp","contentUrl":"https:\/\/schlitzer-destillerie.de\/magazin\/wp-content\/uploads\/2024\/06\/Gin-Lemon-Slushy-Cocktail.webp","width":912,"height":607,"caption":"Cocktail in einem Glas mit Zitronenscheibe, verschwommene Flasche im Hintergrund, bunter Untergrund."},{"@type":"BreadcrumbList","@id":"https:\/\/schlitzer-destillerie.de\/magazin\/erfrischender-citrus-gin-slushy-fuer-den-sommer\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/schlitzer-destillerie.de\/magazin\/"},{"@type":"ListItem","position":2,"name":"Erfrischender Citrus Gin Slushy f\u00fcr den Sommer"}]},{"@type":"WebSite","@id":"https:\/\/schlitzer-destillerie.de\/magazin\/#website","url":"https:\/\/schlitzer-destillerie.de\/magazin\/","name":"Magazin \u2013\u00a0Schlitzer Destillerie","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/schlitzer-destillerie.de\/magazin\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/schlitzer-destillerie.de\/magazin\/#\/schema\/person\/9b641910652a16e469ed3efcce46eaa2","name":"Kai","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/646cb51eb5f7e2bf921a1de93786461c84e696826998c6579c7915d1cb32de1d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/646cb51eb5f7e2bf921a1de93786461c84e696826998c6579c7915d1cb32de1d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/646cb51eb5f7e2bf921a1de93786461c84e696826998c6579c7915d1cb32de1d?s=96&d=mm&r=g","caption":"Kai"}}]}},"_links":{"self":[{"href":"https:\/\/schlitzer-destillerie.de\/magazin\/wp-json\/wp\/v2\/posts\/2218","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/schlitzer-destillerie.de\/magazin\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/schlitzer-destillerie.de\/magazin\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/schlitzer-destillerie.de\/magazin\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/schlitzer-destillerie.de\/magazin\/wp-json\/wp\/v2\/comments?post=2218"}],"version-history":[{"count":6,"href":"https:\/\/schlitzer-destillerie.de\/magazin\/wp-json\/wp\/v2\/posts\/2218\/revisions"}],"predecessor-version":[{"id":2229,"href":"https:\/\/schlitzer-destillerie.de\/magazin\/wp-json\/wp\/v2\/posts\/2218\/revisions\/2229"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/schlitzer-destillerie.de\/magazin\/wp-json\/wp\/v2\/media\/2221"}],"wp:attachment":[{"href":"https:\/\/schlitzer-destillerie.de\/magazin\/wp-json\/wp\/v2\/media?parent=2218"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/schlitzer-destillerie.de\/magazin\/wp-json\/wp\/v2\/categories?post=2218"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/schlitzer-destillerie.de\/magazin\/wp-json\/wp\/v2\/tags?post=2218"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}